{"id":23487,"date":"2025-04-09T07:38:13","date_gmt":"2025-04-09T07:38:13","guid":{"rendered":"https:\/\/www.sundicuttingtools.com\/?p=23487"},"modified":"2025-04-15T09:56:12","modified_gmt":"2025-04-15T09:56:12","slug":"laminas-de-plaina-hss","status":"publish","type":"post","link":"https:\/\/www.sundicuttingtools.com\/pt\/products\/planer-blades\/hss-planer-blades\/","title":{"rendered":"L\u00e2minas de plaina HSS"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"23487\" class=\"elementor elementor-23487\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d615878 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d615878\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c467eb1\" data-id=\"5c467eb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d2da266 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6d2da266\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/HSS-Planer-blades.webp\" alt=\"L\u00e2minas de plaina HSS\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/HSS-Planer-blades-2.webp\" alt=\"L\u00e2minas de plaina HSS\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-33011500\" data-id=\"33011500\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50f8be6d elementor-widget elementor-widget-heading\" data-id=\"50f8be6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">L\u00e2minas de plaina HSS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69b9eb24 elementor-widget elementor-widget-text-editor\" data-id=\"69b9eb24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Sundi fornece produtos de alta qualidade <strong data-start=\"93\" data-end=\"114\">L\u00e2minas de plaina HSS<\/strong> compat\u00edvel com as principais marcas, tais como <strong data-start=\"152\" data-end=\"162\">DeWalt<\/strong>, <strong data-start=\"164\" data-end=\"173\">Delta<\/strong>e muito mais. Estas l\u00e2minas foram concebidas para um aplainamento suave e preciso da madeira, o que as torna uma escolha fi\u00e1vel tanto para uso profissional como para amadores.<\/p><p><strong>Material<b>:<\/b><\/strong> A\u00e7o r\u00e1pido M2 (HSS),W6&amp;HSS18%<\/p><p><strong>Adequado para cortar: <\/strong> Madeira, madeira semi-dura e madeira macia<\/p><p><strong><b>Equipamento: <\/b><\/strong>Moldadoras monofuso, m\u00e1quinas de moldar, plainas de superf\u00edcie, plainas de espessura, plainas de dois lados e plainas de quatro lados para m\u00e1quinas para trabalhar madeira.<\/p><p>Pronto para efetuar uma encomenda? Contacte-nos para obter especifica\u00e7\u00f5es detalhadas, prazos de entrega e quantidade m\u00ednima de encomenda. A Sundi garante um fornecimento est\u00e1vel e uma entrega r\u00e1pida para apoiar as suas necessidades de produ\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254f1e82 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"254f1e82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NDQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obter um or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d728b56 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d728b56\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73980cf5\" data-id=\"73980cf5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-484a79a2 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"484a79a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-thumbs-up\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garantia de qualidade<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-product-hunt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servi\u00e7o OEM\/ODM<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-sort-amount-down\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Redu\u00e7\u00e3o de custos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plane\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrega r\u00e1pida <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82fdfa7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82fdfa7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-696898e\" data-id=\"696898e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7cb2153e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cb2153e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5cb18b2a\" data-id=\"5cb18b2a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-530925 elementor-widget elementor-widget-heading\" data-id=\"530925\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descri\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ca6712f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ca6712f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5722a021\" data-id=\"5722a021\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49749273 elementor-widget elementor-widget-text-editor\" data-id=\"49749273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Em compara\u00e7\u00e3o com as l\u00e2minas de metal duro, <strong data-start=\"96\" data-end=\"117\">L\u00e2minas de plaina HSS<\/strong> s\u00e3o mais afiadas e oferecem melhores arestas de corte para acabamentos finos. Tamb\u00e9m t\u00eam maior resist\u00eancia, reduzindo o risco de lascar ou rachar durante a utiliza\u00e7\u00e3o. No entanto, requerem uma afia\u00e7\u00e3o mais frequente. As l\u00e2minas HSS s\u00e3o normalmente utilizadas para aplainar <strong data-start=\"358\" data-end=\"370\">madeira macia<\/strong> e <strong data-start=\"375\" data-end=\"394\" data-is-only-node=\"\">madeira de folhosas m\u00e9dias<\/strong>, o que as torna ideais para trabalhos de carpintaria de uso geral.<\/p><p>Com mais de 20 anos de experi\u00eancia em ferramentas de corte de precis\u00e3o, a Sundi \u00e9 um fabricante com certifica\u00e7\u00e3o ISO especializado em l\u00e2minas de plaina HSS e outras solu\u00e7\u00f5es para o trabalho da madeira. Quer seja propriet\u00e1rio de uma f\u00e1brica de mobili\u00e1rio, distribuidor de maquinaria para trabalhar a madeira ou um amador experiente, fornecemos produtos fi\u00e1veis e apoio profissional adaptado \u00e0s suas necessidades. O nosso compromisso com uma qualidade consistente, entrega r\u00e1pida e coopera\u00e7\u00e3o a longo prazo conquistou a confian\u00e7a de clientes em todo o mundo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-26df92d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26df92d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5f68577f\" data-id=\"5f68577f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e26682 elementor-widget elementor-widget-text-editor\" data-id=\"55e26682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Carater\u00edsticas:<\/strong><\/p><ul><li class=\"\" data-start=\"90\" data-end=\"196\">\u00a0Elevada efici\u00eancia de corte com resultados limpos e precisos<\/li><li class=\"\" data-start=\"90\" data-end=\"196\">Dispon\u00edvel numa vasta gama de tamanhos padr\u00e3o<\/li><li class=\"\" data-start=\"90\" data-end=\"196\">As arestas afiadas garantem um aplainamento suave e sem rasg\u00f5es<\/li><li class=\"\" data-start=\"90\" data-end=\"196\">Invent\u00e1rio pronto a enviar para a maioria das l\u00e2minas de plaina HSS standard<\/li><li class=\"\" data-start=\"90\" data-end=\"196\">Tamanhos e especifica\u00e7\u00f5es personalizados dispon\u00edveis mediante pedido<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-44464a92 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44464a92\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-70215108\" data-id=\"70215108\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79e1a3a9 elementor-widget elementor-widget-text-editor\" data-id=\"79e1a3a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Especifica\u00e7\u00e3o:<\/strong><\/p><p class=\"\" data-start=\"57\" data-end=\"356\">\u00a0Seguem-se algumas dimens\u00f5es habitualmente utilizadas como refer\u00eancia. Se necessitar de outras especifica\u00e7\u00f5es ou formas personalizadas, n\u00e3o hesite em contactar-nos <a href=\"https:\/\/www.sundicuttingtools.com\/pt\/contactar-nos\/\">contacte-nos.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-705d9dc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"705d9dc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a1ba1f4\" data-id=\"4a1ba1f4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9cf8da elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d9cf8da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"144\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/hss-planer-blades-size.webp\" class=\"attachment-large size-large wp-image-23492\" alt=\"\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/hss-planer-blades-size.webp 900w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/hss-planer-blades-size-300x54.webp 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/hss-planer-blades-size-768x138.webp 768w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/hss-planer-blades-size-18x3.webp 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20a99eac elementor-widget elementor-widget-elementskit-tablepress\" data-id=\"20a99eac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-tablepress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elemenetskit-tablepress ekit-wid-con\" id=\"ekit_tablepress_20a99eac\">\n<table id=\"tablepress-617\" class=\"tablepress tablepress-id-617\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Comprimento (mm)<\/th><th class=\"column-2\">Largura (mm)<\/th><th class=\"column-3\">Espessura (mm)<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">90<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">100<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">120<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">200<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">210<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">250<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">260<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">300<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">310<\/td><td class=\"column-2\">25\/30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">400<\/td><td class=\"column-2\">25\/30\/35<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">410<\/td><td class=\"column-2\">30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">430<\/td><td class=\"column-2\">30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">450<\/td><td class=\"column-2\">30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">500<\/td><td class=\"column-2\">30\/35<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">600<\/td><td class=\"column-2\">30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">630<\/td><td class=\"column-2\">30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">640<\/td><td class=\"column-2\">30<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">400<\/td><td class=\"column-2\">40<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">500<\/td><td class=\"column-2\">40<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">610<\/td><td class=\"column-2\">38<\/td><td class=\"column-3\">6<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">640<\/td><td class=\"column-2\">38<\/td><td class=\"column-3\">6<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-210d2efe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"210d2efe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-79c84b58\" data-id=\"79c84b58\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-399778a9 elementor-widget elementor-widget-image\" data-id=\"399778a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-2.webp\" class=\"attachment-large size-large wp-image-23474\" alt=\"\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-2.webp 800w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-2-300x225.webp 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-2-768x576.webp 768w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-2-16x12.webp 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-28a9bf28\" data-id=\"28a9bf28\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63bcaae4 elementor-widget elementor-widget-image\" data-id=\"63bcaae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-3.webp\" class=\"attachment-large size-large wp-image-23473\" alt=\"\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-3.webp 800w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-3-300x225.webp 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-3-768x576.webp 768w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-3-16x12.webp 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7928070e\" data-id=\"7928070e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23fff3ad elementor-widget elementor-widget-image\" data-id=\"23fff3ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-1.webp\" class=\"attachment-large size-large wp-image-23472\" alt=\"\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-1.webp 800w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-1-300x225.webp 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-1-768x576.webp 768w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/04\/planer-blades-application-1-16x12.webp 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a49f8ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a49f8ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4696d243\" data-id=\"4696d243\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-568d79b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"568d79b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3235565\" data-id=\"3235565\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e848cc6 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"6e848cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Escolha agora l\u00e2minas de plaina de alta qualidade!<\/h2><h3 class=\"ekit-heading--subtitle elementskit-section-subtitle\">\n\t\t\t\t\t\tTodas as informa\u00e7\u00f5es e carregamentos s\u00e3o seguros e confidenciais.\n\t\t\t\t\t<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d4c8c6c\" data-id=\"5d4c8c6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b266b63 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b266b63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NDQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactar agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fa6223c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fa6223c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93abcbc\" data-id=\"93abcbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-104d1122 elementor-widget elementor-widget-heading\" data-id=\"104d1122\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produtos Relacionados\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64c289f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"64c289f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7304e4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7304e4f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ef8c24c\" data-id=\"ef8c24c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7686b7d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7686b7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/laminas-de-plaina-de-metal-duro\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Solid-carbide-planer-blades.jpg\" class=\"attachment-full size-full wp-image-23003\" alt=\"L\u00e2minas de plaina de metal duro\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Solid-carbide-planer-blades.jpg 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Solid-carbide-planer-blades-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/laminas-de-plaina-de-metal-duro\/\">l\u00e2minas de plaina de metal duro<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-523c6b9\" data-id=\"523c6b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2aa8cc1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2aa8cc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/12-laminas-de-plaina-de-1-2-polegadas-para-dewalt-dw734\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Knives-For-DeWALT-DW734.jpg\" class=\"attachment-full size-full wp-image-22997\" alt=\"Facas de plaina para DeWALT DW734\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Knives-For-DeWALT-DW734.jpg 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Knives-For-DeWALT-DW734-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/12-laminas-de-plaina-de-1-2-polegadas-para-dewalt-dw734\/\">L\u00e2minas de plaina de 12-1\/2 polegadas para DeWalt DW734<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0d2cc6e\" data-id=\"0d2cc6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b69935 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8b69935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/laminas-de-plaina-facas-para-plaina-porter-cable-pc305tp\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Blades-Knives-for-Porter-Cable-PC305TP-Planer.jpg\" class=\"attachment-full size-full wp-image-22999\" alt=\"L\u00e2minas de plaina Facas para plaina Porter Cable PC305TP\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Blades-Knives-for-Porter-Cable-PC305TP-Planer.jpg 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Blades-Knives-for-Porter-Cable-PC305TP-Planer-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/laminas-de-plaina-facas-para-plaina-porter-cable-pc305tp\/\">L\u00e2minas de plaina HSS de 12,5 polegadas de substitui\u00e7\u00e3o para a plaina Porter Cable PC305TP<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-12fc9f2\" data-id=\"12fc9f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1896ff0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1896ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/12-inch-planer-blades-for-delta-22-540-planer\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Blades-for-Delta.jpg\" class=\"attachment-full size-full wp-image-22995\" alt=\"L\u00e2minas de plaina para Delta\" srcset=\"https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Blades-for-Delta.jpg 300w, https:\/\/www.sundicuttingtools.com\/wp-content\/uploads\/2025\/02\/Planer-Blades-for-Delta-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.sundicuttingtools.com\/pt\/produtos\/planos-laminas\/12-inch-planer-blades-for-delta-22-540-planer\/\">L\u00e2minas de plaina de 12 polegadas para a plaina Delta 22-540<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>HSS Planer Blades Sundi supplies high-quality HSS planer blades compatible with major brands such as DeWalt, Delta, and more. These blades are designed for smooth and precise wood planing, making them a reliable choice for both professional and hobbyist use. Material: M2 high speed steel (HSS),W6&amp;HSS18% Suitable for cutting: Wood, semi-hardwood, and softwood Equipment: Single-spindle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[909],"tags":[],"class_list":["post-23487","post","type-post","status-publish","format-standard","hentry","category-planer-blades"],"_links":{"self":[{"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/posts\/23487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/comments?post=23487"}],"version-history":[{"count":5,"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/posts\/23487\/revisions"}],"predecessor-version":[{"id":23905,"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/posts\/23487\/revisions\/23905"}],"wp:attachment":[{"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/media?parent=23487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/categories?post=23487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sundicuttingtools.com\/pt\/wp-json\/wp\/v2\/tags?post=23487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}